{"id":13186,"date":"2021-12-07T15:03:21","date_gmt":"2021-12-07T15:03:21","guid":{"rendered":"https:\/\/hemley.de\/product\/krawatte-uni-rips-schwarz-2\/"},"modified":"2026-02-09T14:22:03","modified_gmt":"2026-02-09T14:22:03","slug":"krawatte-uni-rips-schwarz-2","status":"publish","type":"product","link":"https:\/\/hemley.de\/en\/product\/krawatte-uni-rips-schwarz-2\/","title":{"rendered":"Krawatte Seide Rips Uni schwarz"},"content":{"rendered":"<p>gewebte Seidenkrawatte modisch chic gut kombinierbar<\/p>\n","protected":false},"excerpt":{"rendered":"<p>100% Seide Jacquard gewebt<br \/>\nca. 7,5cm x 145cm<br \/>\nSchlaufe aus Oberstoff<br \/>\nZierriegel<br \/>\ngen\u00e4ht in Deutschland<br \/>\nHemley Webetikett und H\u00e4nger<\/p>\n","protected":false},"featured_media":9272,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[406,429,428,531],"product_tag":[],"class_list":{"0":"post-13186","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-hemley-online-shop-en","7":"product_cat-uni_krawatten_online_kaufen-en","8":"product_cat-krawatten-en","9":"product_cat-herbstliche_krawatten_online_kaufen","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Seidenkrawatte handgefertigt in der eigenen Krawattenmanufaktur<\/title>\n<meta name=\"description\" content=\"Elegante Krawatte handgen\u00e4ht in Seide gewebt in der Farbe Schwarz mit Ripsstruktur\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hemley.de\/en\/product\/krawatte-uni-rips-schwarz-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Seidenkrawatte handgefertigt in der eigenen Krawattenmanufaktur\" \/>\n<meta property=\"og:description\" content=\"Elegante Krawatte handgen\u00e4ht in Seide gewebt in der Farbe Schwarz mit Ripsstruktur\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hemley.de\/en\/product\/krawatte-uni-rips-schwarz-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Hemley\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-09T14:22:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hemley.de\/wp-content\/uploads\/2019\/07\/1290004-12.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"368\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hemley.de\\\/en\\\/product\\\/krawatte-uni-rips-schwarz-2\\\/\",\"url\":\"https:\\\/\\\/hemley.de\\\/en\\\/product\\\/krawatte-uni-rips-schwarz-2\\\/\",\"name\":\"Seidenkrawatte handgefertigt in der eigenen Krawattenmanufaktur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hemley.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hemley.de\\\/en\\\/product\\\/krawatte-uni-rips-schwarz-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hemley.de\\\/en\\\/product\\\/krawatte-uni-rips-schwarz-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hemley.de\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/1290004-12.jpg\",\"datePublished\":\"2021-12-07T15:03:21+00:00\",\"dateModified\":\"2026-02-09T14:22:03+00:00\",\"description\":\"Elegante Krawatte handgen\u00e4ht in Seide gewebt in der Farbe Schwarz mit Ripsstruktur\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hemley.de\\\/en\\\/product\\\/krawatte-uni-rips-schwarz-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hemley.de\\\/en\\\/product\\\/krawatte-uni-rips-schwarz-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/hemley.de\\\/en\\\/product\\\/krawatte-uni-rips-schwarz-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hemley.de\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/1290004-12.jpg\",\"contentUrl\":\"https:\\\/\\\/hemley.de\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/1290004-12.jpg\",\"width\":368,\"height\":550,\"caption\":\"1290004-12\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hemley.de\\\/en\\\/product\\\/krawatte-uni-rips-schwarz-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/hemley.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/hemley.de\\\/en\\\/online-shop-vom-hersteller\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Krawatte Seide Rips Uni schwarz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hemley.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/hemley.de\\\/de\\\/\",\"name\":\"Hemley\",\"description\":\"Made in Germany since 1965\",\"publisher\":{\"@id\":\"https:\\\/\\\/hemley.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hemley.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hemley.de\\\/de\\\/#organization\",\"name\":\"Hemley Moese & Schwartz GmbH\",\"url\":\"https:\\\/\\\/hemley.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/hemley.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hemley.de\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Logo-Hemley.png\",\"contentUrl\":\"https:\\\/\\\/hemley.de\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Logo-Hemley.png\",\"width\":467,\"height\":104,\"caption\":\"Hemley Moese & Schwartz GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/hemley.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Seidenkrawatte handgefertigt in der eigenen Krawattenmanufaktur","description":"Elegante Krawatte handgen\u00e4ht in Seide gewebt in der Farbe Schwarz mit Ripsstruktur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hemley.de\/en\/product\/krawatte-uni-rips-schwarz-2\/","og_locale":"en_US","og_type":"article","og_title":"Seidenkrawatte handgefertigt in der eigenen Krawattenmanufaktur","og_description":"Elegante Krawatte handgen\u00e4ht in Seide gewebt in der Farbe Schwarz mit Ripsstruktur","og_url":"https:\/\/hemley.de\/en\/product\/krawatte-uni-rips-schwarz-2\/","og_site_name":"Hemley","article_modified_time":"2026-02-09T14:22:03+00:00","og_image":[{"width":368,"height":550,"url":"https:\/\/hemley.de\/wp-content\/uploads\/2019\/07\/1290004-12.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hemley.de\/en\/product\/krawatte-uni-rips-schwarz-2\/","url":"https:\/\/hemley.de\/en\/product\/krawatte-uni-rips-schwarz-2\/","name":"Seidenkrawatte handgefertigt in der eigenen Krawattenmanufaktur","isPartOf":{"@id":"https:\/\/hemley.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hemley.de\/en\/product\/krawatte-uni-rips-schwarz-2\/#primaryimage"},"image":{"@id":"https:\/\/hemley.de\/en\/product\/krawatte-uni-rips-schwarz-2\/#primaryimage"},"thumbnailUrl":"https:\/\/hemley.de\/wp-content\/uploads\/2019\/07\/1290004-12.jpg","datePublished":"2021-12-07T15:03:21+00:00","dateModified":"2026-02-09T14:22:03+00:00","description":"Elegante Krawatte handgen\u00e4ht in Seide gewebt in der Farbe Schwarz mit Ripsstruktur","breadcrumb":{"@id":"https:\/\/hemley.de\/en\/product\/krawatte-uni-rips-schwarz-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hemley.de\/en\/product\/krawatte-uni-rips-schwarz-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hemley.de\/en\/product\/krawatte-uni-rips-schwarz-2\/#primaryimage","url":"https:\/\/hemley.de\/wp-content\/uploads\/2019\/07\/1290004-12.jpg","contentUrl":"https:\/\/hemley.de\/wp-content\/uploads\/2019\/07\/1290004-12.jpg","width":368,"height":550,"caption":"1290004-12"},{"@type":"BreadcrumbList","@id":"https:\/\/hemley.de\/en\/product\/krawatte-uni-rips-schwarz-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/hemley.de\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/hemley.de\/en\/online-shop-vom-hersteller\/"},{"@type":"ListItem","position":3,"name":"Krawatte Seide Rips Uni schwarz"}]},{"@type":"WebSite","@id":"https:\/\/hemley.de\/de\/#website","url":"https:\/\/hemley.de\/de\/","name":"Hemley","description":"Made in Germany since 1965","publisher":{"@id":"https:\/\/hemley.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hemley.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/hemley.de\/de\/#organization","name":"Hemley Moese & Schwartz GmbH","url":"https:\/\/hemley.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hemley.de\/de\/#\/schema\/logo\/image\/","url":"https:\/\/hemley.de\/wp-content\/uploads\/2019\/05\/Logo-Hemley.png","contentUrl":"https:\/\/hemley.de\/wp-content\/uploads\/2019\/05\/Logo-Hemley.png","width":467,"height":104,"caption":"Hemley Moese & Schwartz GmbH"},"image":{"@id":"https:\/\/hemley.de\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hemley.de\/en\/wp-json\/wp\/v2\/product\/13186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hemley.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/hemley.de\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/hemley.de\/en\/wp-json\/wp\/v2\/comments?post=13186"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hemley.de\/en\/wp-json\/wp\/v2\/media\/9272"}],"wp:attachment":[{"href":"https:\/\/hemley.de\/en\/wp-json\/wp\/v2\/media?parent=13186"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/hemley.de\/en\/wp-json\/wp\/v2\/product_brand?post=13186"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hemley.de\/en\/wp-json\/wp\/v2\/product_cat?post=13186"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hemley.de\/en\/wp-json\/wp\/v2\/product_tag?post=13186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}